{"id":137708,"date":"2020-10-06T00:00:00","date_gmt":"2020-10-06T00:00:00","guid":{"rendered":"https:\/\/www.iplay.com\/games\/bear-haven-motel\/"},"modified":"2020-10-06T00:00:00","modified_gmt":"2020-10-06T00:00:00","slug":"bear-haven-motel","status":"publish","type":"product","link":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/","title":{"rendered":"Bear Haven Motel"},"content":{"rendered":"<p>Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;! Il y a une temporaire, eh bien&#8230; manque d\u2019invit\u00e9s en ce moment, alors ne vous inqui\u00e9tez pas. Nous avons \u00e9galement des probl\u00e8mes inhabituels avec notre syst\u00e8me \u00e9lectrique la nuit, mais nous sommes convaincus que vous serez en mesure de les r\u00e9soudre. N\u2019oubliez pas que si quelque chose est cass\u00e9 \u00e0 6h00 du matin, vous serez licenci\u00e9 ! Alors ne laissez pas passer une occasion de gagner un gros salaire pour votre travail. Oui&#8230; Et maintenant, pour nos invit\u00e9s sp\u00e9ciaux. Ne vous mettez pas en travers de leur chemin. Si quelque chose ne va pas, fuyez. Apr\u00e8s cela, fermez la porte et \u00e9teignez la lumi\u00e8re. Pendant que vous vous cachez vous, le t\u00e9l\u00e9phone ne doit pas sonner et la t\u00e9l\u00e9vision ne doit pas \u00eatre allum\u00e9e. Ensuite, vous pourrez survivre \u00e0 la premi\u00e8re nuit terrifiante !           <\/p>\n<p>&nbsp;<\/p>\n<p><strong>Fonctionnalit\u00e9s:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&#8211; Bear Haven est un fantastique jeu d\u2019horreur ind\u00e9pendant dans lequel vous devez survivre \u00e0 des nuits terrifiantes.<br \/>\n&#8211; Veuillez garder \u00e0 l\u2019esprit qu\u2019il ne s\u2019agit pas d\u2019un autre clone de Five Nights at Freddy\u2019s.<br \/>\n&#8211; En tant qu\u2019agent de s\u00e9curit\u00e9 de nuit, vous n\u2019\u00eates pas limit\u00e9 \u00e0 regarder les cam\u00e9ras, mais vous \u00eates \u00e9galement capable de vous d\u00e9placer et de vous engager dans la zone.<br \/>\n&#8211; Participez \u00e0 une exp\u00e9rience cauchemardesque immersive et captivante.<br \/>\n&#8211; R\u00e9parez l\u2019\u00e9lectricit\u00e9 cass\u00e9e et cachez-vous des ours furieux pour qu\u2019ils ne puissent pas vous trouver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!<\/p>\n","protected":false},"author":131,"featured_media":81954,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[202],"product_tag":[],"class_list":["post-137708","product","type-product","status-publish","has-post-thumbnail","product_cat-removed-content-fr","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bear Haven Motel - Jouez le r\u00f4le d\u2019un \u00e9lectricien de motel, r\u00e9solvant des \u00e9nigmes<\/title>\n<meta name=\"description\" content=\"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bear Haven Motel\" \/>\n<meta property=\"og:description\" content=\"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/\" \/>\n<meta property=\"og:site_name\" content=\"IPlay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/\",\"url\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/\",\"name\":\"Bear Haven Motel - Jouez le r\u00f4le d\u2019un \u00e9lectricien de motel, r\u00e9solvant des \u00e9nigmes\",\"isPartOf\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg\",\"datePublished\":\"2020-10-06T00:00:00+00:00\",\"description\":\"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage\",\"url\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg\",\"contentUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg\",\"width\":310,\"height\":310},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.iplay.com\/fr\/home-page-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.iplay.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bear Haven Motel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.iplay.com\/en\/#website\",\"url\":\"https:\/\/www.iplay.com\/en\/\",\"name\":\"IPlay\",\"description\":\"The Best Casual Games!\",\"publisher\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.iplay.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.iplay.com\/en\/#organization\",\"name\":\"IPlay\",\"url\":\"https:\/\/www.iplay.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg\",\"contentUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg\",\"width\":98,\"height\":25,\"caption\":\"IPlay\"},\"image\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bear Haven Motel - Jouez le r\u00f4le d\u2019un \u00e9lectricien de motel, r\u00e9solvant des \u00e9nigmes","description":"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/","og_locale":"fr_FR","og_type":"article","og_title":"Bear Haven Motel","og_description":"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!","og_url":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/","og_site_name":"IPlay","og_image":[{"width":310,"height":310,"url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/","url":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/","name":"Bear Haven Motel - Jouez le r\u00f4le d\u2019un \u00e9lectricien de motel, r\u00e9solvant des \u00e9nigmes","isPartOf":{"@id":"https:\/\/www.iplay.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage"},"image":{"@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg","datePublished":"2020-10-06T00:00:00+00:00","description":"Bienvenue \u00e0 votre nouveau poste d\u2019\u00e9lectricien \u00e0 temps partiel au Bear Haven Motel&nbsp;!","breadcrumb":{"@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#primaryimage","url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg","contentUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/12\/large_square_tile_image-2628.jpg","width":310,"height":310},{"@type":"BreadcrumbList","@id":"https:\/\/www.iplay.com\/fr\/games\/bear-haven-motel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iplay.com\/fr\/home-page-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.iplay.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bear Haven Motel"}]},{"@type":"WebSite","@id":"https:\/\/www.iplay.com\/en\/#website","url":"https:\/\/www.iplay.com\/en\/","name":"IPlay","description":"The Best Casual Games!","publisher":{"@id":"https:\/\/www.iplay.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iplay.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.iplay.com\/en\/#organization","name":"IPlay","url":"https:\/\/www.iplay.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg","contentUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg","width":98,"height":25,"caption":"IPlay"},"image":{"@id":"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product\/137708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/comments?post=137708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/media\/81954"}],"wp:attachment":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/media?parent=137708"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_brand?post=137708"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_cat?post=137708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_tag?post=137708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}