{"id":131638,"date":"2025-04-16T09:30:47","date_gmt":"2025-04-16T09:30:47","guid":{"rendered":"https:\/\/www.iplay.com\/?post_type=product&p=131638"},"modified":"2025-04-15T11:10:13","modified_gmt":"2025-04-15T11:10:13","slug":"detectives-united-mission-possible-collectors-edition","status":"publish","type":"product","link":"https:\/\/www.iplay.com\/fr\/games\/detectives-united-mission-possible-collectors-edition\/","title":{"rendered":"Detectives United: Mission Possible Collector&#8217;s Edition"},"content":{"rendered":"<p>Un monde palpitant o\u00f9 se combinent danger, myst\u00e8re et travail d\u2019\u00e9quipe attend d\u2019\u00eatre d\u00e9couvert dans le dernier chapitre de la c\u00e9l\u00e8bre s\u00e9rie Detectives United. La paisible ville de Myst Hill s\u2019est transform\u00e9e en un \u00e9picentre du chaos, alors que la paix est perturb\u00e9e par une s\u00e9rie de disparitions myst\u00e9rieuses et d\u2019observations d\u2019animaux bizarres. Apr\u00e8s un terrible accident de voiture, l\u2019\u00e9quipe a \u00e9t\u00e9 s\u00e9par\u00e9e et une course contre la montre doit \u00eatre entreprise pour se r\u00e9unir, d\u00e9couvrir la v\u00e9rit\u00e9 et emp\u00eacher une sinistre organisation de d\u00e9manteler Detectives United pour toujours.  <\/p>\n<p>Vos personnages pr\u00e9f\u00e9r\u00e9s peuvent \u00eatre incarn\u00e9s, chacun \u00e9tant \u00e9quip\u00e9 de capacit\u00e9s uniques, car des d\u00e9fis immersifs sont relev\u00e9s tout au long du jeu. Des chronologies interconnect\u00e9es sont explor\u00e9es, des \u00e9nigmes complexes sont r\u00e9solues et des personnages sombres sont confront\u00e9s dans cette aventure rapide de puzzle d\u2019objets cach\u00e9s. Les forces qui travaillent contre vous doivent \u00eatre d\u00e9jou\u00e9es et la survie de votre \u00e9quipe doit \u00eatre assur\u00e9e. Jamais les enjeux n\u2019ont \u00e9t\u00e9 aussi \u00e9lev\u00e9s !   <\/p>\n<p>&nbsp;<\/p>\n<p><strong>Caract\u00e9ristiques de l\u2019\u00e9dition collector<\/strong><\/p>\n<ul>\n<li><strong>Chapitre bonus :<\/strong> Un agent qui a \u00e9t\u00e9 accus\u00e9 \u00e0 tort doit \u00eatre disculp\u00e9 dans cette aventure suppl\u00e9mentaire.<\/li>\n<li><strong>Valeur de rejouabilit\u00e9 :<\/strong> Les sc\u00e8nes d\u2019objets cach\u00e9s et les mini-jeux pr\u00e9f\u00e9r\u00e9s peuvent \u00eatre rejou\u00e9s, avec des succ\u00e8s gagn\u00e9s en cours de route.<\/li>\n<li><strong>Collection:<\/strong> Des dizaines de figurines et de pi\u00e8ces de puzzle cach\u00e9es attendent d\u2019\u00eatre chass\u00e9es et de collecter des pi\u00e8ces pour \u00eatre compl\u00e9t\u00e9es.<\/li>\n<li><strong>Extras exclusifs :<\/strong> Un tr\u00e9sor comprenant des \u00e9conomiseurs d\u2019\u00e9cran, des bandes sonores, des fonds d\u2019\u00e9cran, une pi\u00e8ce secr\u00e8te et bien plus encore est d\u00e9bloqu\u00e9 pour votre plus grand plaisir.<\/li>\n<li><strong>Guide strat\u00e9gique :<\/strong> Votre chemin ne sera jamais perdu gr\u00e2ce au guide de strat\u00e9gie complet qui est gard\u00e9 \u00e0 port\u00e9e de main.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s &#8211; R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !<\/p>\n","protected":false},"author":17,"featured_media":131583,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[148,165],"product_tag":[287],"class_list":["post-131638","product","type-product","status-publish","has-post-thumbnail","product_cat-adventure-fr","product_cat-hidden-object-fr","product_tag-play-on-pc-fr","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aventure \u00e9pique d\u2019objets cach\u00e9s : faites la course pour sauver Myst Hill !<\/title>\n<meta name=\"description\" content=\"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detectives United: Mission Possible Collector&#039;s Edition\" \/>\n<meta property=\"og:description\" content=\"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/\" \/>\n<meta property=\"og:site_name\" content=\"IPlay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/\",\"url\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/\",\"name\":\"Aventure \u00e9pique d\u2019objets cach\u00e9s : faites la course pour sauver Myst Hill !\",\"isPartOf\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp\",\"datePublished\":\"2025-04-16T09:30:47+00:00\",\"description\":\"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage\",\"url\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp\",\"contentUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp\",\"width\":715,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.iplay.com\/fr\/home-page-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.iplay.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Detectives United: Mission Possible Collector&#8217;s Edition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.iplay.com\/en\/#website\",\"url\":\"https:\/\/www.iplay.com\/en\/\",\"name\":\"IPlay\",\"description\":\"The Best Casual Games!\",\"publisher\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.iplay.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.iplay.com\/en\/#organization\",\"name\":\"IPlay\",\"url\":\"https:\/\/www.iplay.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg\",\"contentUrl\":\"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg\",\"width\":98,\"height\":25,\"caption\":\"IPlay\"},\"image\":{\"@id\":\"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aventure \u00e9pique d\u2019objets cach\u00e9s : faites la course pour sauver Myst Hill !","description":"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/","og_locale":"fr_FR","og_type":"article","og_title":"Detectives United: Mission Possible Collector's Edition","og_description":"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !","og_url":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/","og_site_name":"IPlay","og_image":[{"width":715,"height":485,"url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/","url":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/","name":"Aventure \u00e9pique d\u2019objets cach\u00e9s : faites la course pour sauver Myst Hill !","isPartOf":{"@id":"https:\/\/www.iplay.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage"},"image":{"@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp","datePublished":"2025-04-16T09:30:47+00:00","description":"Faites la course pour sauver Myst Hill dans cette aventure palpitante d\u2019objets cach\u00e9s - R\u00e9unissez votre \u00e9quipe de d\u00e9tectives et arr\u00eatez une sinistre organisation avant qu\u2019il ne soit trop tard !","breadcrumb":{"@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#primaryimage","url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp","contentUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2025\/04\/detectives_united_mission_possible_ce_large_video_screenshot.webp","width":715,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/www.iplay.com\/en\/games\/detectives-united-mission-possible-collectors-edition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iplay.com\/fr\/home-page-2\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.iplay.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Detectives United: Mission Possible Collector&#8217;s Edition"}]},{"@type":"WebSite","@id":"https:\/\/www.iplay.com\/en\/#website","url":"https:\/\/www.iplay.com\/en\/","name":"IPlay","description":"The Best Casual Games!","publisher":{"@id":"https:\/\/www.iplay.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iplay.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.iplay.com\/en\/#organization","name":"IPlay","url":"https:\/\/www.iplay.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg","contentUrl":"https:\/\/www.iplay.com\/wp-content\/uploads\/2023\/11\/Group-6100.svg","width":98,"height":25,"caption":"IPlay"},"image":{"@id":"https:\/\/www.iplay.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product\/131638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/comments?post=131638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/media\/131583"}],"wp:attachment":[{"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/media?parent=131638"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_brand?post=131638"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_cat?post=131638"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.iplay.com\/fr\/wp-json\/wp\/v2\/product_tag?post=131638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}